{"id":6954,"date":"2013-01-27T11:10:00","date_gmt":"2013-01-27T14:10:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=6954"},"modified":"2014-08-13T03:43:49","modified_gmt":"2014-08-13T06:43:49","slug":"tudo-pertence-ao-pai-2","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/tudo-pertence-ao-pai-2\/","title":{"rendered":"Tudo pertence ao Pai"},"content":{"rendered":"<div id=\"foto\" style=\"margin: 0pt auto;padding: 5px;width: 180px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2013\/janeiro\/27_pe-alessandro-001.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Padre Alessandro<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p> Todos n&oacute;s constru&iacute;mos e vivemos nossa vida numa expectativa daquilo que &eacute; a nossa realiza&ccedil;&atilde;o plena como homem e, principalmente, como filhos de Deus. Nossa vida &eacute; uma eterna conquista em busca da felicidade. Por que esse desejo est&aacute; t&atilde;o presente em nossa vida? Porque o Senhor colocou em n&oacute;s a pr&oacute;pria vida.<\/p>\n<p>  Nas coisas que n&atilde;o encontramos felicidade, n&atilde;o encontramos vida. Vida e felicidade caminham juntas. Essa vida em plenitude &eacute; a nossa realiza&ccedil;&atilde;o como inteiro, em todas as dimens&otilde;es que dizem respeito ao ser humano. Mas, nessa busca incessante de felicidade, n&oacute;s a procuramos onde ela n&atilde;o est&aacute;.<\/p>\n<p>  Nenhum de n&oacute;s peca porque gosta de pecar, mas pecamos porque temos a ilus&atilde;o de que aquele pecado vai nos trazer felicidade plena. <\/p>\n<p>  Se n&oacute;s olharmos os Evangelhos veremos que todas as a&ccedil;&otilde;es de Jesus, neste mundo, s&oacute; tiveram uma raz&atilde;o: glorificar o Pai. Seu maior desejo &eacute; mostrar que tudo pertence ao Pai e torn&aacute;-Lo conhecido por n&oacute;s.<\/p>\n<p>  Quando tomamos consci&ecirc;ncia que tudo que somos e possu&iacute;mos pertence a Deus, nossa vida passa a ter um novo sentido, porque compreendemos que nossos desejos e sonhos passam pela vontade d&#039;Aquele que nos criou.<\/p>\n<p>O Senhor n&atilde;o nos tira do sofrimento, mas nos d&aacute; a gra&ccedil;a de suport&aacute;-los e, principalmente, super&aacute;-los. Quando o Pai nos d&aacute; a gra&ccedil;a para enfrentar as tribula&ccedil;&otilde;es, ela permanece conosco e faz com que sejamos cada vez mais fortes.<\/p>\n<p>  O pr&oacute;prio Jesus Cristo orou intercedendo junto ao Pai por n&oacute;s, na sua &uacute;ltima ora&ccedil;&atilde;o, conhecida como a ora&ccedil;&atilde;o sacerdotal. Neste momento, ele clamou a Deus: &ldquo;Pai, olhai por eles&rdquo;.<\/p>\n<p>  O que vale para n&oacute;s hoje &eacute; a vida que vivemos para Deus.  As coisas deste mundo n&atilde;o importam para Jesus, pois a &uacute;nica pergunta que Ele nos far&aacute; quando chegar nossa hora ser&aacute;: &ldquo;Como voc&ecirc; viveu sua vida?&rdquo;.<\/p>\n<p>  Por este motivo, nossa presen&ccedil;a nesse mundo precisa manifestar a presen&ccedil;a do pr&oacute;prio Cristo. <\/p>\n<p>Um crit&eacute;rio muito f&aacute;cil para saber se, realmente, estamos vivendo uma vida voltada para Deus &eacute; nos perguntarmos se, em todos os lugares que estamos frequentando, Jesus tamb&eacute;m poderia ir ou se os amigos que mantemos tamb&eacute;m poderiam ser amigos de Deus.<\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;padding: 5px;width: 370px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2013\/janeiro\/27_pe-alessandro-003.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&quot;O que vale para n&oacute;s &eacute; a vida que vivemos para Deus&quot;, diz padre Alessandro.<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>  Reflita sobre tudo que voc&ecirc; viveu at&eacute; hoje, principalmente as dificuldades, e pense em quantas delas Deus permaneceu em sil&ecirc;ncio. O crist&atilde;o que passa por isso e permanece firme em sua f&eacute; apresenta ao mundo o sinal de uma f&eacute; madura.<\/p>\n<p>  Deus se cala por um instante para mostrar Seu amor depois. Assim foi com Seu pr&oacute;prio Filho na cruz, quando Ele silenciou, para que tr&ecirc;s dias depois pudesse ressuscit&aacute;-Lo. &Eacute; exatamente isso que o Senhor quer fazer com voc&ecirc;, pois as tribula&ccedil;&otilde;es servem para nos manter firmes na f&eacute; e nos encaminhar para a vit&oacute;ria final.<\/p>\n<p>  Entregue sua vida ao Senhor, principalmente aquilo de que voc&ecirc; precisa se livrar, pois &eacute; exatamente isso que Ele quer receber. Se hoje for o &uacute;ltimo dia da sua vida, Deus quer que voc&ecirc; esteja pronto para a vida eterna, sem nada para lamentar ou se arrepender.<\/p>\n<p>Transcri&ccedil;&atilde;o e adapta&ccedil;&atilde;o: Gustavo Souza<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Padre Alessandro Foto: Cancaonova.com Todos n&oacute;s constru&iacute;mos e vivemos nossa vida numa expectativa daquilo que &eacute; a nossa realiza&ccedil;&atilde;o plena como homem e, principalmente, como filhos de Deus. Nossa vida &eacute; uma eterna conquista em busca da felicidade. Por que&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/6954"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=6954"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/6954\/revisions"}],"predecessor-version":[{"id":6955,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/6954\/revisions\/6955"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=6954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=6954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=6954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}