{"id":7139,"date":"2013-12-24T17:00:00","date_gmt":"2013-12-24T20:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=7139"},"modified":"2023-11-17T14:48:04","modified_gmt":"2023-11-17T17:48:04","slug":"hoje-nasceu-para-nos-o-salvador-que-e-cristo-o-senhor","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/natal-na-cancao-nova\/pregacoes\/hoje-nasceu-para-nos-o-salvador-que-e-cristo-o-senhor\/","title":{"rendered":"Hoje nasceu para n\u00f3s o Salvador, que \u00e9 Cristo, o Senhor"},"content":{"rendered":"<p><strong>Esse \u00e9 o grande anuncio: \u201cHoje nasceu para n\u00f3s o Salvador, que \u00e9 Cristo, o Senhor\u201d.<\/strong><\/p>\n<p>A liturgia atualiza a hist\u00f3ria da salva\u00e7\u00e3o. Pela liturgia, o Natal acontece hoje, os anjos anunciaram aos pastores: \u201cHoje, nasceu para n\u00f3s o Salvador, que \u00e9 Cristo, o Senhor\u201d.<\/p>\n<p>A primeira leitura tr\u00e1s profecia a de Isa\u00edas: \u201cO povo, que andava na escurid\u00e3o, viu uma grande luz; para os que habitavam nas sombras da morte, uma luz resplandeceu\u201d. A humanidade estava habitando na sombra da morte, e Jesus veio para aqueles que habitavam na sombra da morte. Houve uma mudan\u00e7a radical na humanidade, Ele veio iluminar.<\/p>\n<p>A profecia continua:\u00a0\u201cPorque nasceu para n\u00f3s um menino, foi-nos dado um filho; Ele traz aos ombros a marca da realeza; o nome que lhe foi dado \u00e9: Conselheiro admir\u00e1vel, Deus forte, Pai dos tempos futuros, Pr\u00edncipe da paz\u201d.<\/p>\n<p>Jesus \u00e9 Rei, Ele veio na simplicidade de uma crian\u00e7a, Ele veio na pobreza, mas Ele era Rei, e n\u00e3o era um rei qualquer, Ele \u00e9 o Rei do c\u00e9u e da terra, o poderoso e o alt\u00edssimo.<\/p>\n<h3>Jesus veio ser o Conselheiro admir\u00e1vel!<\/h3>\n<p>O Pai do c\u00e9u quer ser para voc\u00ea um conselheiro admir\u00e1vel.<\/p>\n<p>Na sua fragilidade, na sua fraqueza, o Pai te deu um Deus forte, nasceu na manjedoura, na simplicidade, mas um Deus forte.<\/p>\n<p>Somos fracos, erramos, ca\u00edmos, mas Deus est\u00e1 ao nosso lado, Ele caminha conosco, um Deus forte que vem em auxilio \u00e0 nossa fraqueza.<\/p>\n<p>Voc\u00ea deve assumir a Jesus como seu Pai para toda eternidade, mesmo quando voc\u00ea erra, fracassa, Ele \u00e9 seu pai e ser\u00e1 Pai para sempre. E o bonito \u00e9 saber que temos um pai para sempre.<\/p>\n<p>E continua o profeta Isa\u00edas a nos descrever, dizendo que Ele \u00e9 Pr\u00edncipe da paz, ou seja, Ele governa a paz. Onde n\u00e3o h\u00e1 paz, Ele envia a paz. Hoje, voc\u00ea pode falar para Jesus que voc\u00ea deseja a paz, que, na sua fam\u00edlia, impere a paz.<\/p>\n<p>Pe\u00e7amos que, neste Brasil t\u00e3o violento, haja paz e vivamos na paz.<\/p>\n<p>Na segunda leitura, um grande an\u00fancio onde S\u00e3o Paulo diz a Tito e a cada um de n\u00f3s.<\/p>\n<p>\u201cCar\u00edssimo, a gra\u00e7a de Deus se manifestou trazendo salva\u00e7\u00e3o para todos os homens\u201d. Deus quer que esta salva\u00e7\u00e3o chegue para todos, at\u00e9 mesmo aquele que, em sua casa, desonrou a fam\u00edlia, para a pessoa que te apunhalou pelas costas, a pessoa que te feriu e te machucou, Deus quer salva\u00e7\u00e3o.<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.10151865472594632.1073741911.45027114631&amp;type=1\">Veja mais foto no facebook<\/a><\/p>\n<p>A leitura da Carta de S\u00e3o Paulo a Tido ainda nos ensina a abandonar a impiedade e as paix\u00f5es mundanas, a viver neste mundo com equil\u00edbrio, justi\u00e7a e piedade, nos ensina a abandonar a impiedade e as paix\u00f5es mundanas, e tamb\u00e9m a viver neste mundo com equil\u00edbrio, justi\u00e7a e piedade, aguardando a feliz esperan\u00e7a e a manifesta\u00e7\u00e3o da gl\u00f3ria do nosso grande Deus e Salvador, Jesus Cristo. Quando S\u00e3o Paulo escreveu isso para Tito e para sua comunidade, Cristo j\u00e1 havia nascido, morrido e ressuscitado, S\u00e3o Paulo est\u00e1 dizendo da segunda vinda de Jesus.<\/p>\n<p>Celebremos o Natal de Jesus, e a Igreja faz com que olhemos mais longe, aguardando a feliz esperan\u00e7a e a manifesta\u00e7\u00e3o da gl\u00f3ria do nosso grande Deus e Salvador, Jesus Cristo.<\/p>\n<p>Gente, \u00e9 certo, Jesus voltar\u00e1, isso n\u00e3o \u00e9 para nos causar medo, e sim para causar alegria, esperamos Jesus que vem colher os frutos da salva\u00e7\u00e3o, que Ele mesmo nos trouxe.<\/p>\n<p>Rompa com o pecado! Na Can\u00e7\u00e3o Nova, temos uma grande lema\u00a0\u201cPHN\u201d (Por hoje n\u00e3o), por hoje n\u00e3o vou mais pecar, isso repetido a cada novo dia, e, caso a gente falhe, n\u00f3s levantamos e confessamos. \u00c9 preciso a ruptura com o pecado, para fazer parte daqueles os quais Jesus vai colher para a gl\u00f3ria.<\/p>\n<p>\u00c9 preciso uma vida santa, uma vida de Eucaristia, de leitura da Palavra, de devo\u00e7\u00e3o filial a Nossa Senhora, uma vida de verdade, de amor, de justi\u00e7a, de honestidade, de entrega aos outros. Diga n\u00e3o ao pecado e sim \u00e0 santidade.<\/p>\n<p>Hoje, no Natal, estamos fazendo o prop\u00f3sito do desejo pelo c\u00e9u. N\u00e3o podemos perder o nosso lugar no c\u00e9u.<\/p>\n<p>_______________________________________<\/p>\n<p><strong>Prega\u00e7\u00e3o realizada no dia 24 de dezembro de 2013<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esse \u00e9 o grande anuncio: \u201cHoje nasceu para n\u00f3s o Salvador, que \u00e9 Cristo, o Senhor\u201d. A liturgia atualiza a hist\u00f3ria da salva\u00e7\u00e3o. Pela liturgia, o Natal acontece hoje, os anjos anunciaram aos pastores: \u201cHoje, nasceu para n\u00f3s o Salvador,&#8230;<\/p>\n","protected":false},"author":114,"featured_media":68199,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"aliane","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/7139"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=7139"}],"version-history":[{"count":8,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/7139\/revisions"}],"predecessor-version":[{"id":71359,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/7139\/revisions\/71359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/68199"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=7139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=7139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=7139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}