{"id":7232,"date":"2012-02-09T06:40:00","date_gmt":"2012-02-09T09:40:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=7232"},"modified":"2014-08-13T03:58:00","modified_gmt":"2014-08-13T06:58:00","slug":"jesus-o-bom-pastor","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/jesus-o-bom-pastor\/","title":{"rendered":"Jesus, o Bom Pastor"},"content":{"rendered":"<div id=\"foto\" style=\"width: 180px;margin: 0pt auto;padding: 5px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2012\/Fevereiro\/09_eventos-001.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Padre Jo&atilde;o Gualberto<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida\/cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<div align=\"justify\">N&atilde;o importa a situa&ccedil;&atilde;o em que voc&ecirc; hoje est&aacute;, acredite no que Deus falou a nosso respeito: &ldquo;Eu vos amo com amor eterno&rdquo;. E no momento que voc&ecirc; est&aacute; vivendo hoje, acolha essa Palavra.<\/p>\n<p>  N&oacute;s precisamos acreditar nas cria&ccedil;&otilde;es de Deus, pois mais do que filhos d&#039;Ele, devemos ser testemunhas das Suas realiza&ccedil;&otilde;es.<\/p>\n<p>  Nossa exist&ecirc;ncia foi desejada pelo Alt&iacute;ssimo, a cria&ccedil;&atilde;o do homem e da mulher foi essencial para que a obra do mundo fizesse sentido. E com isso, o Senhor nos deu uma identidade para que pud&eacute;ssemos nos diferenciar uns dos outros.<\/p>\n<p>  O Senhor n&atilde;o &eacute; um pai ou uma m&atilde;e irrespons&aacute;vel, pois Ele d&aacute; sustento a tudo o que cria. E, desde o in&iacute;cio, nos deu a liberdade, assim como a que Ele possui. A diferen&ccedil;a &eacute; que, com Sua liberdade, jamais usou de mentiras, trai&ccedil;&otilde;es ou falsas identidades.<\/p>\n<p>  O homem, em sua liberdade, um dia tomou a decis&atilde;o errada, se distraiu e caiu na tenta&ccedil;&atilde;o sobre a qual Deus j&aacute; o havia advertido. E assim, como &eacute; nas nossas vidas, o mal se utilizou de sutileza e ast&uacute;cia, e, pela ambi&ccedil;&atilde;o do homem, fez com que n&oacute;s ca&iacute;ssemos em pecado.<\/p>\n<p>  Mesmo assim, Deus n&atilde;o se acomoda e vai ao encontro do homem, dando a garantia de que n&oacute;s n&atilde;o iremos nos perder. Ele faz a alian&ccedil;a com Seu povo, dando-nos a possibilidade de pisar na tenta&ccedil;&atilde;o e renunciar ao pecado.<\/p>\n<p>  Assim como o pastor, que se preocupa em cuidar das suas ovelhas, o Pai tem o cuidado de acompanhar Seus filhos, levando-nos para &aacute;guas limpas, fornecendo nosso sustento e nos orientando com rela&ccedil;&atilde;o aos perigos que vamos enfrentar.<\/p>\n<p>  O objetivo de Deus n&atilde;o &eacute; outro sen&atilde;o salvar o homem. E essa salva&ccedil;&atilde;o n&atilde;o se d&aacute; pela metade, mas sim por inteiro. Prova disso foi ter enviado Seu Filho &uacute;nico e amado para viver entre n&oacute;s, n&atilde;o se contentando apenas em falar conosco por vis&otilde;es e palavras de profetas.<\/p>\n<p>  Precisamos retomar a comunica&ccedil;&atilde;o com Deus ao nos aproximar de Jesus, o Bom Pastor, deixando todas as coisas e pessoas que nos afastam d&#039;Ele. Busque conhecer a Sua Igreja, a Palavra e os ensinamentos de Deus, n&atilde;o fique no superficialismo, vivendo em &aacute;guas rasas.<\/p>\n<div id=\"foto\" style=\"width: 370px;margin: 0pt auto;padding: 5px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2012\/Fevereiro\/09_eventos-002.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&quot;Voc&ecirc; &eacute; convidado a ser pastor onde quer que esteja&quot;, exorta padre Jo&atilde;o Gualberto<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida\/cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>  Decida-se pelo caminho reto, fazendo com que sua intimidade com Deus fale mais alto do que os sentimentos mundanos, caso contr&aacute;rio, ter&aacute; o mesmo destino da ovelha que se perdeu do seu rebanho.<\/p>\n<p>  Hoje voc&ecirc; &eacute; convidado a ser pastor onde quer que esteja. Voc&ecirc; que &eacute; pai ou m&atilde;e tem a obriga&ccedil;&atilde;o de conduzir seus filhos pelo caminho de Deus. Ser&aacute; que hoje voc&ecirc; tem cuidado bem dos seus rebanhos?<\/p>\n<p>  Devemos nos voltar para a finalidade para o qual fomos criados. A restaura&ccedil;&atilde;o do original em nossa vida precisa ser nossa luta di&aacute;ria, n&atilde;o podemos mais viver de momentos vazios.<\/p>\n<p>  Deus tem um des&iacute;gnio para cada um de n&oacute;s, por isso, seja uma ovelha honesta, e sempre que for necess&aacute;rio, tenha coragem de conduzir o rebanho para boas pastagens. Seja como o Bom Pastor, que sempre foi manso e humilde de cora&ccedil;&atilde;o, aliviando o fardo daqueles que est&atilde;o cansados pelas feridas causadas pelos pr&oacute;prios erros.<\/p><\/div>\n<div align=\"justify\">&nbsp;<\/div>\n<div align=\"justify\"><em>Transcri&ccedil;&atilde;o e adapta&ccedil;&atilde;o: Gustavo Souza <\/em><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Padre Jo&atilde;o Gualberto Foto: Wesley Almeida\/cancaonova.com N&atilde;o importa a situa&ccedil;&atilde;o em que voc&ecirc; hoje est&aacute;, acredite no que Deus falou a nosso respeito: &ldquo;Eu vos amo com amor eterno&rdquo;. E no momento que voc&ecirc; est&aacute; vivendo hoje, acolha essa Palavra&#8230;.<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/7232"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=7232"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/7232\/revisions"}],"predecessor-version":[{"id":7233,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/7232\/revisions\/7233"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=7232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=7232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=7232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}