{"id":7342,"date":"2012-06-28T11:00:00","date_gmt":"2012-06-28T14:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=7342"},"modified":"2014-08-13T04:01:26","modified_gmt":"2014-08-13T07:01:26","slug":"deus-tem-compaixao-das-nossas-feridas","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/deus-tem-compaixao-das-nossas-feridas\/","title":{"rendered":"Deus tem compaix\u00e3o das nossas feridas"},"content":{"rendered":"<div id=\"foto\" style=\"width: 180px;margin: 0pt auto;float: right;padding: 5px\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/cancaonova.com\/portal\/arquivos\/fotos\/2012\/junho\/28_eventos-006.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&quot;Deus tem compaix&atilde;o da sua les&atilde;o e se debru&ccedil;a sobre ela&quot;, disse Ir. Maria Eunice<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida\/Cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>Vamos deixar que o Esp&iacute;rito Santo aja e interceda por n&oacute;s. Talvez voc&ecirc; pense que o Ele venha de algum lugar, mas o Esp&iacute;rito Santo &eacute; Deus, Aquele que nos revela, ensina e advoga nossas causas juntos ao Senhor. &Eacute; este Esp&iacute;rito que  habita em n&oacute;s e  move  a nossa vida.<\/p>\n<p>Diga estas Palavras do Evangelho: &quot;Em verdade, em verdade, v&oacute;s digo: quem n&atilde;o nascer de novo n&atilde;o poder&aacute; ver o reino de Deus&quot;. Pe&ccedil;a a Deus para abrir seu  cora&ccedil;&atilde;o ao Esp&iacute;rito Santo.<\/p>\n<p>Neste tempo de gra&ccedil;a, somos convidados a olhar para o cora&ccedil;&atilde;o transpassado do Senhor e depositar nele as nossas enfermidades interiores.<\/p>\n<p>S&atilde;o tantas as feridas internas que carregamos; e nesta ferida exposta de Jesus vamos pedir as curas para as nossas chagas. Muitas vezes, n&oacute;s nos encontramos perdidos, e quem nos encontra &eacute; Jesus. Por isso seu cora&ccedil;&atilde;o ficou transpassado para salvar  a cada um de n&oacute;s.<\/p>\n<p>  Quando o cora&ccedil;&atilde;o de Jesus foi apunhalado  pela lan&ccedil;a pontiaguda do soldado e jorrou sangue e &aacute;gua, a humanidade foi curada das suas chagas. &Eacute; ao lado do Senhor que voc&ecirc; pode curar todos seus machucados.<\/p>\n<p>S&oacute; em Deus vamos encontrar a cura das nossas feridas interiores, pois o cora&ccedil;&atilde;o d&#039;Ele foi doado a n&oacute;s.&nbsp;O maior sacramento de cura interior &eacute; a comunh&atilde;o. S&oacute; o homem  pode se alimentar do Corpo e do Sangue de Cristo para que Ele se torne vida em n&oacute;s, curando todas as nossas les&otilde;es.<\/p>\n<p>  Entregue suas enfermidades a Deus, porque voc&ecirc; foi chamado a amar mais e melhor. Deposite no cora&ccedil;&atilde;o d&#039;Ele as feridas que est&atilde;o abertas em seu cora&ccedil;&atilde;o: s&atilde;o traumas emocionais, interiores, que recebemos ao longo da caminhada. &Eacute; preciso que voc&ecirc; cure estes machucados.<\/p>\n<p>  O mundo est&aacute; repleto de pessoas com ferimentos abertos. Deus tem compaix&atilde;o da sua les&atilde;o e se debru&ccedil;a sobre ela, porque Ele &eacute; a eterna miseric&oacute;rdia. A palavra &quot;miseric&oacute;rdia&quot; &eacute; t&atilde;o forte que esconde  dois significados importantes: mis&eacute;ria e cora&ccedil;&atilde;o. Isso &eacute; Deus, compadecido do nosso sofrimento e curando todos as nossas amarguras. <\/p>\n<p>  Precisamos estar no cora&ccedil;&atilde;o de Deus, pois Ele &eacute; o Cordeiro que  tira todos os pecados do mundo. Portanto, &eacute; preciso retirar esta dor, mas n&atilde;o  podemos nos entregar ao pecado, &nbsp;ainda mais depois que Jesus nos deu livre acesso ao Seu cora&ccedil;&atilde;o. De maneira nenhuma, deixe-se entregar ao pecado, porque n&atilde;o podemos nos tornar escravos deste mal.<\/p>\n<p>  Todos somos pecadores e n&atilde;o podemos nos entregar,  porque o Senhor veio at&eacute; n&oacute;s  e deixou a porta do Seu cora&ccedil;&atilde;o aberta para  que deixemos ali nossos pecados.<\/p>\n<div id=\"foto\" style=\"width: 370px;margin: 0pt auto;float: none;padding: 5px\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/cancaonova.com\/portal\/arquivos\/fotos\/2012\/junho\/28_eventos-005.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&quot;N&atilde;o existe sofrimento algum que Deus n&atilde;o possa curar&quot;, afirma Ir. Maria Eunice<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO--><font color=\"#000000\">Foto: Wesley Almeida\/Cancaonova.com<\/font><!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p><font color=\"#000000\"><br \/>Deus cuida de n&oacute;s, portanto, entregue suas enfermidades e as retire do seu cora&ccedil;&atilde;o.  A minha cura est&aacute;  nas &#039;chagas gloriosas&#039; de Cristo, portanto lan&ccedil;ai suas mis&eacute;rias. Se n&atilde;o nos utilizarmos de Suas chagas para nos curarmos, n&atilde;o entraremos no Reino dos C&eacute;us.<\/p>\n<p>  Hoje, temos uma alian&ccedil;a de sangue com Jesus, pois Ele veio  at&eacute; n&oacute;s para curar todos os males do mundo. N&atilde;o importa o tamanho da sua amargura, da sua dor e da sua tristeza, &nbsp;&eacute; preciso que  voc&ecirc;  entregue estes sentimentos na cruz de Jesus, pois Ele &eacute; a cura e a for&ccedil;a.<\/p>\n<p>  N&atilde;o existe sofrimento algum que Deus n&atilde;o possa curar. Quando voc&ecirc; tiver uma grande dor, seja ela qual for, olhe para cruz e para a chaga aberta; tenha a certeza de que &eacute; dali que  vem  o rem&eacute;dio.<\/font><\/p>\n<p><font color=\"#000000\">&nbsp;<\/font><\/p>\n<p><font color=\"#000000\">&nbsp;<\/font><\/p>\n<p><font color=\"#000000\"><em>Transcri&ccedil;&atilde;o e adapta&ccedil;&atilde;o:&nbsp; Alessandra Borges<\/em><\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&quot;Deus tem compaix&atilde;o da sua les&atilde;o e se debru&ccedil;a sobre ela&quot;, disse Ir. Maria Eunice Foto: Wesley Almeida\/Cancaonova.com Vamos deixar que o Esp&iacute;rito Santo aja e interceda por n&oacute;s. Talvez voc&ecirc; pense que o Ele venha de algum lugar, mas&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/7342"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=7342"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/7342\/revisions"}],"predecessor-version":[{"id":7343,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/7342\/revisions\/7343"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=7342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=7342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=7342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}