{"id":810,"date":"2007-09-14T17:00:00","date_gmt":"2007-09-14T20:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=810"},"modified":"2020-12-21T21:18:22","modified_gmt":"2020-12-22T00:18:22","slug":"jesus-o-salvador-do-mundo","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/acampamento-de-cura-e-libertacao\/pregacoes\/jesus-o-salvador-do-mundo\/","title":{"rendered":"Jesus: o Salvador do mundo"},"content":{"rendered":"<p>Certa vez fui numa livraria e l\u00e1 eu vi um pequeno livro com o t\u00edtulo &#8220;O Evangelho em muitas l\u00ednguas&#8221;. Comprei aquele livro, e vi que apenas um vers\u00edculo do Evangelho era traduzida. Quis saber por que aquela frase era t\u00e3o importante para ser chamada de Evangelho e para muita gente essa palavra era o resumo do Evangelho inteiro.<\/p>\n<p>A Palavra est\u00e1 em Jo\u00e3o 3,16: <em>\u201cCom efeito, de tal modo Deus amou o mundo, que lhe deu seu Filho \u00fanico, para que todo o que nele crer n\u00e3o pere\u00e7a, mas tenha a vida eterna\u201d.<\/em> Eu espero que voc\u00eas nunca esque\u00e7am esse vers\u00edculo. Ele cont\u00e9m os seis elementos mais importantes da proclama\u00e7\u00e3o do Evangelho:<\/p>\n<p><strong>1\u00ba &#8211;<\/strong> Quem \u00e9 Este que nos amou? S\u00e3o Jo\u00e3o diz que Deus nos ama. \u00c9 simples, Deus nos ama, pode ter algo mais simples que isso?<\/p>\n<p><strong>2\u00ba &#8211;<\/strong> A quem Deus ama? S\u00e3o Jo\u00e3o diz que Deus amou tanto o mundo, que n\u00e3o \u00e9 mundo da natureza, \u00e9 a pessoa. Por isso que todas as vezes que Jo\u00e3o fala dessa parte ele fala com grande avers\u00e3o, ele fala dessa palavra mundo como se n\u00e3o gostasse dela. Jo\u00e3o fala: \u201cEsse mundo que eu n\u00e3o gosto Deus amou tanto\u201d. Voc\u00ea quer saber que mundo \u00e9 esse que Jo\u00e3o tinha avers\u00e3o? \u00c9 esse mundo que voc\u00ea ver no jornal todos os dias. Apesar de todas as descobertas do mundo hoje, elas tem tornado o mundo melhor para se viver? S\u00e3o Jo\u00e3o diz que esse mundo \u00e9 t\u00e3o mal e ainda Deus o ama. A quem Deus ama? N\u00e3o s\u00f3 as pessoas santas, mas tamb\u00e9m as pecadoras.<\/p>\n<p><strong>3\u00ba &#8211;<\/strong> De que forma Deus ama o mundo? A prova do amor de Deus \u00e9 que Ele deu seu \u00fanico Filho, tudo que Ele tinha de precioso que era Seu \u00fanico Filho. Para o cristianismo Jesus \u00e9 sinal do amor de Deus.<\/p>\n<p><strong>4\u00ba &#8211; <\/strong>Por que Deus deu Seu Filho? Ele deu Seu Filho para que n\u00f3s n\u00e3o morr\u00eassemos e nem f\u00f4ssemos oprimidos pelo inimigo de Deus. Ent\u00e3o usamos a linguagem do Evangelho, o Senhor enviou Seu Filho para que pud\u00e9ssemos ser salvos.<\/p>\n<p><strong>5\u00ba &#8211;<\/strong> O Senhor enviou seu Filho para que pud\u00e9ssemos viver uma vida nova, e Jesus diz em Jo\u00e3o 10,10: <em>\u201cEu vim para que as ovelhas tenham vida e para que a tenham em abund\u00e2ncia.\u201d<\/em> Todos que acreditam nessa vida nova.<\/p>\n<p><strong>6\u00ba &#8211;<\/strong> Qual a condi\u00e7\u00e3o que o Senhor pede a cada um de n\u00f3s? S\u00e3o Jo\u00e3o diz que n\u00e3o h\u00e1 nenhuma condi\u00e7\u00e3o. O que significa isso: Para aqueles que cr\u00eaem? Significa que eu n\u00e3o tenho que fazer nada para que eu tenha vida nova, mas devo acreditar que, se eu deixar, Jesus faz novas todas as coisas.<\/p>\n<p>Para qualquer crist\u00e3o essa \u00e9 a Palavra mais importante: Jo\u00e3o 3, 16: <em>\u201cCom efeito, de tal modo Deus amou o mundo, que lhe deu seu Filho \u00fanico, para que todo o que nele crer n\u00e3o pere\u00e7a, mas tenha a vida eterna\u201d.<\/em><\/p>\n<p><strong>Vou contar um caso de liberta\u00e7\u00e3o de algu\u00e9m por quem eu rezei:<\/p>\n<p><\/strong>Eu tive que dar um retiro para umas Irm\u00e3s Carmelitas na \u00cdndia. Quando eu fui ver a sala de palestra, a capela, eu vi uma cruz, a maior cruz que eu j\u00e1 havia visto em uma capela, e quando eu olhei para ela a figura de Jesus parecia estar viva.<\/p>\n<p>Eu senti que havia algo santo na capela, ent\u00e3o eu disse para as irm\u00e3s que todo retiro seria na capela, Missa, ora\u00e7\u00f5es e palestras. Foi a primeira vez que eu fiz aquilo, ent\u00e3o assim come\u00e7amos o retiro.<\/p>\n<p>No segundo dia de retiro eu recebi a carta de uma mulher, escrita por um padre famoso da \u00cdndia, que dizia: \u201cPrezado, padre Rufus, eu estou te enviando essa mulher porque ela precisa de ajuda, de liberta\u00e7\u00e3o porque h\u00e1 20 anos ela tem tido possess\u00f5es\u201d.<\/p>\n<p>A mulher me disse que havia 20 anos que ela ca\u00eda na rua sem motivo e via em determinados lugares como se dem\u00f4nios tivessem surgindo.<\/p>\n<p>O que eu fiz? Eu n\u00e3o me esqueci daquela cruz. Normalmente eu teria rezado por ela numa sala, mas eu a trouxe para a capela e coloquei-a diante da cruz. Quando eu olhei para ela, ela ainda n\u00e3o tinha olhado para cruz. Eu perguntei quem \u00e9 voc\u00ea? A reposta foi: \u201cPor que voc\u00ea est\u00e1 me fazendo essa pergunta? N\u00f3s nos j\u00e1 encontramos outras vezes\u201d.<\/p>\n<p>Eu n\u00e3o perguntei mais, ent\u00e3o ela olhou para a cruz e ali todo o inferno apareceu, e ela come\u00e7ou a dizer palavras duras para Jesus. \u201cPor que voc\u00ea me trouxe aqui diante de Ti? Essa casa \u00e9 minha? Eu estava aqui h\u00e1 20 anos eu tenho que sair porque voc\u00ea ainda est\u00e1 nesta cruz, des\u00e7a da cruz\u201d.<\/p>\n<p>E como nada estava acontecendo ele come\u00e7ou a dizer palavras sujas para Jesus, que a irm\u00e3 que estava traduzindo n\u00e3o podia repetir. Ent\u00e3o eu me lembrei das passagens do Evangelho em que os fariseus diziam para Jesus descer da cruz para que as pessoas acreditarem n\u2019Ele. Eu percebi que quem estava dizendo para Jesus descer da cruz h\u00e1 dois mil anos era o esp\u00edrito mal, o mesmo que estava na mulher. Mesmo o ladr\u00e3o que estava na cruz disse isso para Jesus, e como Jesus n\u00e3o desceu da cruz o ladr\u00e3o come\u00e7ou a amaldi\u00e7o\u00e1-Lo.<\/p>\n<p>Eu percebi que a \u00faltima tenta\u00e7\u00e3o de Jesus foi no Monte Calv\u00e1rio, e n\u00e3o foram somente tr\u00eas vezes foram quatro vezes. O inimigo colocou a palavra na boca dos soldados e das pessoas que por l\u00e1 passavam e agora eu estava ouvindo dos l\u00e1bios daquela mulher, mas Jesus n\u00e3o se rendeu. Jesus morreu por n\u00f3s, Ele foi crucificado por n\u00f3s. Percebi qual foi a \u00faltima tenta\u00e7\u00e3o de Jesus.<\/p>\n<p>Quando Jesus disse que iria ser crucificado, Pedro disse que isso n\u00e3o aconteceria, quem disse n\u00e3o foi Pedro, por isso Jesus lhe disse: \u201cAfasta de mim satan\u00e1s\u201d. Imagine Jesus dizendo isso para o primeiro Papa. Satan\u00e1s usou at\u00e9 de Pedro, o primeiro Papa para que Jesus n\u00e3o fosse crucificado. O que o Papa atual nos diz, ele escreveu uma <span style=\"color: #0033cc\"><strong><a title=\"Mensagem de Bento XVI para Quaresma 2007\" href=\"http:\/\/www.cancaonova.com\/portal\/canais\/news2\/news.php?id=24416\" target=\"_blank\" rel=\"noopener\">carta<\/a><\/strong><\/span>, olhem para Aquele que voc\u00eas crucificaram, n\u00e3o pedindo para Ele descer da cruz.<\/p>\n<p>A mulher dizia coisas horr\u00edveis, mas Jesus n\u00e3o desceu da cruz porque Ele j\u00e1 tinha vencido. O que eu podia fazer para aquela mulher? Nada. Ent\u00e3o eu repeti as palavras da Missa: <strong>\u201cPor sua cruz e ressurrei\u00e7\u00e3o o Senhor nos libertou. Tu \u00e9s o Salvador do mundo\u201d.<\/strong> Eu fiz ora\u00e7\u00e3o de liberta\u00e7\u00e3o para aquela mulher? N\u00e3o. Jesus j\u00e1 tinha morrido na cruz para ela.<\/p>\n<p>Quando eu estava rezando por ela eu perguntei: Por que voc\u00ea possui essa mulher? E ele pelo poder o Esp\u00edrito Santo me disse que quando essa mulher, antes de se casar, para ir a igreja ela tinha que passar debaixo de uma \u00e1rvore e ele estava na \u00e1rvore, ela era bonita ele se apaixonou e entrou nela.<\/p>\n<p>Como o inimigo pode possuir uma jovem passando debaixo da \u00e1rvore? Essa mulher quando era adolescente queria entrar no convento, mas os pais queriam que ela casasse. Ela come\u00e7ou a desobedecer aos pais. Ser freira \u00e9 bom, mas talvez essa n\u00e3o era a vontade de Deus na vida dela. A coisa n\u00e3o \u00e9 ser bom ou ruim, mas se \u00e9 vontade de Deus.<\/p>\n<p>Ela n\u00e3o admitia n\u00e3o ser freira, ficou ofendida contra os seus pais, criou uma amargura e ressentimento por eles, e ao passar debaixo da \u00e1rvore indo para igreja esses sentimentos fizeram com que ela estivesse aberta para o inimigo.<\/p>\n<p>Eu perguntei: O que aconteceu quando voc\u00ea passou debaixo daquela \u00e1rvore? Ela sentiu que caiu algo nela, parecia ser uma flor, mas n\u00e3o viu nada. S\u00e3o os sentimentos ruins que fazem com que sejamos atacados. A partir daquele dia tudo dava errado na vida dela. Quando o padre perguntou se ela aceitava aquele rapaz ela n\u00e3o conseguia dizer, a m\u00e3e teve que ajudar. Quando ela olhava as fotos do casamento era como se ela n\u00e3o tivesse ali.<\/p>\n<p>Depois da ora\u00e7\u00e3o ela se sentiu livre, eu fiz com que ela perdoasse os pais e aceitasse o casamento. No momento em que estava terminando a conversa percebi que ela estava gr\u00e1vida, quase nove meses. Ela disse que todos faziam a mesma pergunta para ela, mas ela n\u00e3o estava gr\u00e1vida, mas quando ela casou j\u00e1 estava assim. Ela passou a sentir sentimentos de gr\u00e1vida desde quando algo caiu na cabe\u00e7a dela debaixo da \u00e1rvore, porque o inimigo n\u00e3o queria que ela se casasse com ningu\u00e9m, por isso a deixou com esses sentimentos.<\/p>\n<p>Eu a levei diante do crucifixo porque aquele era um sinal de que o inimigo ainda estava a perturbando. Eu fiz uma ora\u00e7\u00e3o e ela caiu no ch\u00e3o inconsciente, eu j\u00e1 sabia que n\u00e3o era gravidez natural, eu toquei de leve o estomago dela e disse: Em nome de Jesus sai de dentro dessa pessoa, e minha m\u00e3o desceu e todo aquele incha\u00e7o saiu de dentro dela. Foi uma libera\u00e7\u00e3o instant\u00e2nea.<\/p>\n<p>Eu gostaria que voc\u00ea visse o que eu vi, porque Jesus morreu numa cruz por nossos pecados. Foi uma opera\u00e7\u00e3o natural, obra do Esp\u00edrito Santo de Jesus que morreu por n\u00f3s numa cruz.<\/p>\n<p><em>Transcri\u00e7\u00e3o e edi\u00e7\u00e3o: Willieny Isaias<\/em><\/p>\n<p align=\"center\">\n","protected":false},"excerpt":{"rendered":"<p>Certa vez fui numa livraria e l\u00e1 eu vi um pequeno livro com o t\u00edtulo &#8220;O Evangelho em muitas l\u00ednguas&#8221;. Comprei aquele livro, e vi que apenas um vers\u00edculo do Evangelho era traduzida. Quis saber por que aquela frase era&#8230;<\/p>\n","protected":false},"author":114,"featured_media":52753,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"aliane","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/810"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=810"}],"version-history":[{"count":4,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/810\/revisions"}],"predecessor-version":[{"id":59122,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/810\/revisions\/59122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/52753"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}