{"id":8859,"date":"2008-01-24T06:40:00","date_gmt":"2008-01-24T09:40:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=8859"},"modified":"2014-08-13T04:50:26","modified_gmt":"2014-08-13T07:50:26","slug":"o-mais-belo-dos-filhos-dos-homens%c2%94","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/o-mais-belo-dos-filhos-dos-homens%c2%94\/","title":{"rendered":"O mais belo dos filhos dos homens!\u0094"},"content":{"rendered":"<div id=\"foto\" style=\"margin: 0pt auto;padding: 10px 0px 10px 10px;width: 180px;float: right\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2008\/janeiro\/24_quinta-003.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Padre Roberto<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Robson Siqueira<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>Nesta Quinta-feira de Adora&ccedil;&atilde;o ao Sant&iacute;ssimo Sacramento, queremos pedir ao Senhor que a nossa alma, que o nosso interior possa aprender a viver cada momento, cada experi&ecirc;ncia, daquilo que Ele tem feito e realizado em n&oacute;s. A alegria de poder ver o Senhor. Como Ele se manifesta e como &eacute; belo poder ver Jesus no Sant&iacute;ssimo Sacramento, a sua beleza escondida, &uacute;nica, real, pessoal! E &eacute; esta experi&ecirc;ncia que queremos viver neste dia. Experi&ecirc;ncia que vivemos na Santa Missa e a Igreja rompe o tempo e se me permitem dizer: quase que o [tempo] &ldquo;desrespeitando&rdquo;.<\/p>\n<p>  Quero come&ccedil;ar com uma passagem que os Santos Padres sempre meditavam em suas cartas:<em> &ldquo;Sois belo, o mais belo dos filhos dos homens&rdquo;<\/em> (Salmo 44\/45,3). Esta passagem &eacute; muito anunciada no tempo da Paix&atilde;o de Jesus, pois n&oacute;s cat&oacute;licos temos uma admira&ccedil;&atilde;o pelo &lsquo;Mist&eacute;rio Eucar&iacute;stico&rsquo; dentro de n&oacute;s: adorar a Deus no v&eacute;u do Sacramento. Se n&oacute;s cat&oacute;licos n&atilde;o temos uma admira&ccedil;&atilde;o e sentimos alegria num culto supremo de adora&ccedil;&atilde;o, nenhum mist&eacute;rio vai parar dentro de n&oacute;s. <\/p>\n<p>  Esta admira&ccedil;&atilde;o por Ele, que &eacute; mais belo entre os filhos dos homens, &eacute; confirmada por S&atilde;o Paulo: <em>&ldquo;Sendo ele de condi&ccedil;&atilde;o divina, n&atilde;o se prevaleceu de sua igualdade com Deus, mas aniquilou-se a si mesmo, assumindo a condi&ccedil;&atilde;o de escravo e assemelhando-se aos homens&rdquo;<\/em> (Filipenses 2,6-7), assumindo a natureza humana menos o pecado. <\/p>\n<p>  N&oacute;s queremos hoje nos encontrar com o Senhor, a nossa alma est&aacute; aqui, queremos levantar aqui hoje um culto de adora&ccedil;&atilde;o e dizer: &ldquo;Jesus, &eacute;s Filho mais belo entre os homens!&rdquo; <\/p>\n<p>  Eu repito: se voc&ecirc;, cat&oacute;lico, perdeu o encanto, a alegria por Jesus no Sacramento pode ter certeza de que vai perdendo, perdendo, perdendo cada vez mais essa admira&ccedil;&atilde;o. Muitos n&atilde;o se alegram mais com a presen&ccedil;a de Jesus no Sacramento, n&atilde;o se importam em busc&aacute;-Lo, n&atilde;o desejam mais v&ecirc;-Lo, estar na presen&ccedil;a d&rsquo;Ele e ador&aacute;-Lo. <\/p>\n<p>  Esta passagem do Salmo &eacute; uma passagem Eucar&iacute;stica e nos d&aacute; o encanto do cora&ccedil;&atilde;o do Senhor, a alegria de estar na presen&ccedil;a d&rsquo;Ele; e nos d&oacute;i o cora&ccedil;&atilde;o quando os cat&oacute;licos perdem a gra&ccedil;a, perdem o encanto e a felicidade por ver e estar com Ele. <\/p>\n<p>  Imagine se eu &ndash; como sacerdote &ndash; subisse ao altar para consagrar o p&atilde;o e o vinho e n&atilde;o tivesse a alegria de estar com Nosso Senhor Jesus Cristo Senhor? Ali est&aacute; Aquele que pode encher o meu cora&ccedil;&atilde;o [referindo-se a Jesus]. <strong>Mas parece que a dureza do cora&ccedil;&atilde;o vai se fazendo presente nos meus irm&atilde;os; os tabern&aacute;culos vazios, as Santas Missas frias, Jesus esquecido, abandonado,<\/strong> tanto que chegar&aacute; um tempo em que tudo o que &eacute; belo para o Senhor ser&aacute; proibido; tudo que alegra o cora&ccedil;&atilde;o do Senhor ser&aacute; proibido! <\/p>\n<p>   Tudo isso &eacute; t&atilde;o apartado, negligenciado, por t&atilde;o sublime presen&ccedil;a e chegar&aacute; um tempo em que um sacerdote bem paramentado vai ser zombado ao celebrar a Santa Missa&#8230; E, hoje, infelizmente isso j&aacute; acontece, de forma que parece ter valor aquele sacerdote que celebra de qualquer maneira. &Eacute; por isso que eu disse que a Carta aos Filipenses &eacute; a alma de Jesus no altar, Ele &eacute; o alimento vivo, palpitante em sua vida! N&atilde;o podemos deixar que o cora&ccedil;&atilde;o fique g&eacute;lido na presen&ccedil;a d&rsquo;Ele! <\/p>\n<p>  Por isso que um cat&oacute;lico &ndash; que n&atilde;o tem mais admira&ccedil;&atilde;o pelo mist&eacute;rio [da consagra&ccedil;&atilde;o do Corpo e Sangue de Cristo e de toda a Igreja] &ndash;, como vai entender a dor (e creio que voc&ecirc; est&aacute; entendendo o que digo ao seu cora&ccedil;&atilde;o), como vai entender o sofrimento dos pobres se n&atilde;o entende como o Cordeiro [Jesus Cristo] &eacute; sacrificado no altar? <\/p>\n<p>  Conversando com Dom Cl&aacute;udio, ele disse que estava triste, pois houve uma seculariza&ccedil;&atilde;o na vida consagrada feminina tamb&eacute;m, perdeu-se o amor, perdeu-se o mist&eacute;rio da vida consagrada e o amor por Jesus. Est&aacute; se retirando o mist&eacute;rio de tudo, tamb&eacute;m na vida do leigo a cada dia se est&aacute; retirando o mist&eacute;rio, deixando-o cada vez mais g&eacute;lido. Voc&ecirc; precisa alimentar a sua f&eacute;, precisa acreditar no mist&eacute;rio, tem de ir n&atilde;o com a raz&atilde;o, mas com a emo&ccedil;&atilde;o e sentimentos. <\/p>\n<p>  Ora, um homem consagrado, uma mulher consagrada, que perdeu o desejo de comungar o mist&eacute;rio da f&eacute;, como pode entender a sua vida de consagrado? Voc&ecirc; precisa entender o caminho da dor, o caminho do abandono, por isso a Santa Missa &eacute; ato de sacrif&iacute;cio, embora alguns te&oacute;logos queiram dizer que esta &eacute; um simples ato, um rito. Quando voc&ecirc; participa da Celebra&ccedil;&atilde;o Eucar&iacute;stica, faz parte &ldquo;contempor&acirc;nea&rdquo; com Jesus, o que significa ser do mesmo tempo, da mesma &eacute;poca em que vivemos, hoje. Por isso a Missa &eacute; um ato do Senhor. <\/p>\n<p>  Se voc&ecirc; est&aacute; com vontade de chorar, chore; se est&aacute; com dor, coloque-a no altar, e lembre-se de que voc&ecirc; n&atilde;o &eacute; inocente como Jesus; s&oacute; Ele &eacute; inocente. Muitos ateus, quando morre um amigo deles, colocam a culpa em Deus e julgam que ningu&eacute;m tem direito de sofrer. <\/p>\n<p>  Voc&ecirc; deve entender que o Senhor &eacute; a &uacute;nica resposta da sua dor. Fa&ccedil;a d&rsquo;Ele a raz&atilde;o da sua vida! Eu sei que voc&ecirc; est&aacute; entendendo isso no cora&ccedil;&atilde;o: O mais belo do Filho dos homens est&aacute; ao nosso redor. &Eacute; Ele que vem e entra dentro de n&oacute;s, que nos alimenta e s&oacute; Ele &eacute; o Inocente entrando na sua vida para lhe dar sabedoria &ndash; diante tantos momentos que voc&ecirc; vive e de tantos questionamentos, como: &ldquo;Por que meu filho de 12 anos foi morrer assim?&rdquo; ou &ldquo;Por que meu filho est&aacute; doente?&rdquo;, etc. Quantos s&atilde;o os casais que aprenderam a amar por terem filhos com S&iacute;ndrome de Down, lembrando-se de que Jesus &eacute; o Inocente, o Cordeiro, pois n&atilde;o abriu a boca contra aqueles que O maltrataram. Ele era o mais belo do Filho dos homens e ningu&eacute;m queria olhar para Ele diz o profeta Isa&iacute;as [ap&oacute;s a flagela&ccedil;&atilde;o e morte]. <\/p>\n<p>  Filhos e filhas, &eacute; neste ponto que lhes falo do car&aacute;ter sacramental da Santa Missa. Guardem primeiro a passagem: <em>&ldquo;Tu &eacute;s Filho mais belo&#8230;&rdquo;<\/em> na qual podemos crer no Cordeiro, que entra em nossas vidas, alimentando-nos a alma; e que o cat&oacute;lico, a cat&oacute;lica, que perdeu a gra&ccedil;a, n&atilde;o conseguir&aacute; chegar a algum lugar. A Igreja espera o seu cora&ccedil;&atilde;o sedento pelo V&eacute;u do Sacramento do Filho dos homens. <strong>No sorriso dos inocentes est&aacute; Jesus Cristo. <\/strong><\/p>\n<p>  Dom Cl&aacute;udio disse que est&aacute; dif&iacute;cil trabalhar com as voca&ccedil;&otilde;es, pois o mist&eacute;rio foi esquecido e na nova igreja de S&atilde;o Pio na It&aacute;lia Nosso Senhor Jesus Cristo est&aacute; abandonado, jogado, ultrajado, esquecido no segundo andar em uma capela fria. <\/p>\n<p>   Tomem o profeta Isa&iacute;as no cap&iacute;tulo 53, vers&iacute;culo 2, que diz: &ldquo;Cresceu diante dele como um pobre rebento enraizado numa terra &aacute;rida; n&atilde;o tinha gra&ccedil;a nem beleza para atrair nossos olhares, e seu aspecto n&atilde;o podia seduzir-nos&rdquo;. At&eacute; parece que o profeta fala contra o salmista, mas n&atilde;o &eacute;. O profeta diz que Jesus era o mais belo passando pelo sofrimento; quantos O tratam com zombaria&#8230; <\/p>\n<p>  Quando voc&ecirc; quer fazer o sacrif&iacute;cio e &eacute; ultrajado &eacute; quando tem de continuar. E bendito seja Deus pelos sacerdotes que t&ecirc;m continuado a tratar Jesus como Ele merece! Pois casa, carro, o &ldquo;fundador santo&rdquo; n&atilde;o s&atilde;o o bastante para se encontrar com Jesus. O Senhor deu para n&oacute;s Sua gra&ccedil;a e a Sua beleza no sofrimento e n&oacute;s as temos, pois o Esp&iacute;rito Santo nos d&aacute; a gra&ccedil;a e a beleza de Jesus. <\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;width: 370px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2008\/janeiro\/24_quinta-004.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Jesus, &eacute;s Filho mais belo entre os homens, afirma Padre Roberto<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Robson Siqueira<br \/><!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>Sem Jesus no V&eacute;u do Sacramento n&atilde;o se pode viver e duvido se um cat&oacute;lico verdadeiro vive sem a presen&ccedil;a do Sacramento! Que venham aqueles que n&atilde;o t&ecirc;m vergonha por causa de Jesus Sacramentado! E padres que desejam, ardentemente, celebrar com fervor o mist&eacute;rio Eucar&iacute;stico! <\/p>\n<p>  <strong>Esta express&atilde;o de amor o conduz ao sofrimento dos inocentes. Hoje por causa da recess&atilde;o dos Estados Unidos, por causa do Iraque, entre outros, quantos n&atilde;o v&atilde;o morrer de fome!<\/strong> A morte dos inocentes, como o pobre de rua, aquele que n&atilde;o tem atendimento m&eacute;dico nem uma palavra de amor. Como um casal que tem a &lsquo;gra&ccedil;a&rsquo; de ter um filho com S&iacute;ndrome de Down, ambos transformam o amor presentes neles e potencializam esse sentimento. <\/p>\n<p> A Santa Missa &eacute; a celebra&ccedil;&atilde;o suprema. Jesus &eacute; a beleza do Pai. H&aacute; a alegria de poder ver Jesus Sacramentado, pois ap&oacute;s a consagra&ccedil;&atilde;o n&atilde;o h&aacute; mais p&atilde;o, mas &eacute; o meu Senhor que se faz presente no altar. Se voc&ecirc; n&atilde;o tem mais encanto pelo Sacramento, voc&ecirc; vai perder tudo, at&eacute; sua pr&oacute;pria vida. Tenha certeza de que n&atilde;o ir&aacute; se desviar dos caminhos que Deus tem para voc&ecirc;, nem perca a inoc&ecirc;ncia, hoje um dom t&atilde;o precioso e raro. Precisamos voltar a crer no amor puro, voltar a acreditar na lealdade do cora&ccedil;&atilde;o dos outros e que h&aacute; homens e mulheres santos na sua vida, assim como que Jesus est&aacute; em nosso cora&ccedil;&atilde;o!<br \/>  Filipenses 2,6: Nela est&atilde;o contidas duas passagens que eu usei na prega&ccedil;&atilde;o: <em>&ldquo;Sendo ele de condi&ccedil;&atilde;o divina, n&atilde;o se prevaleceu de sua igualdade com Deus [&#8230;] assemelhando-se aos homens.&rdquo;<\/em> Sem deixar de ser Deus, Cristo aniquilou-se e na celebra&ccedil;&atilde;o da Santa Missa Ele n&atilde;o se torna p&atilde;o, mas sim, um sacrif&iacute;cio, no qual podemos &ldquo;comer&rdquo; Deus. Ele &eacute; comido por toda a Igreja, Ele &eacute; degustado e isso n&atilde;o &eacute; simbolismo. Muitos tentam torn&aacute;-Lo um simbolismo, mas a verdade &eacute; que Jesus foi dado em sacrif&iacute;cio perfeito. Na Santa Missa, voc&ecirc; se torna servo, ela n&atilde;o forma orgulhosos, ela forma servos. Largue o orgulho de n&atilde;o dar direito a um pecador recome&ccedil;ar; o orgulho de n&atilde;o querer ser humilhado, por isso a Missa perde o valor para alguns cat&oacute;licos, que se afastam de Jesus por n&atilde;o estarem junto d&rsquo;Ele. <\/p>\n<p>  Eu convido voc&ecirc; para nunca perder a gra&ccedil;a e o encanto por Jesus no V&eacute;u do Sacramento. Lembrando que a Santa Missa &eacute; um culto de sacrif&iacute;cio, que nos escolhe e nos torna servos perfeitos, conduzindo-nos e preparando-nos para a vida eterna.  Quando eu vejo um fragmento de H&oacute;stia Consagrada, que se perde, eu digo &agrave; minha alma:  &ldquo;Tu &eacute;s o mais belo entre todos&rdquo;; no menor fragmento est&aacute; o mais belo de todos os homens! E se eu perder a beleza pelo menor fragmento, vou perder a gra&ccedil;a por todo o Sacramento: do sacerd&oacute;cio, da minha vida.  <\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Transcri&ccedil;&atilde;o: Rog&eacute;rio Viana<\/em>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Padre Roberto Foto: Robson Siqueira Nesta Quinta-feira de Adora&ccedil;&atilde;o ao Sant&iacute;ssimo Sacramento, queremos pedir ao Senhor que a nossa alma, que o nosso interior possa aprender a viver cada momento, cada experi&ecirc;ncia, daquilo que Ele tem feito e realizado em&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/8859"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=8859"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/8859\/revisions"}],"predecessor-version":[{"id":8860,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/8859\/revisions\/8860"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=8859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=8859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=8859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}