{"id":8929,"date":"2008-04-17T14:00:00","date_gmt":"2008-04-17T17:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=8929"},"modified":"2014-08-13T04:52:43","modified_gmt":"2014-08-13T07:52:43","slug":"nosso-passaporte-e-visto-para-o-ceu","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/nosso-passaporte-e-visto-para-o-ceu\/","title":{"rendered":"Nosso passaporte e visto para o c\u00e9u"},"content":{"rendered":"<p><a href=\"http:\/\/vobr.webtvcn.com\/2008\/abril\/padroflores.mp3\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/cnova\/ministerio\/materias\/images\/03eos300d.jpg\" border=\"0\" width=\"72\" height=\"22\" align=\"left\" \/><\/a><a href=\"http:\/\/vobr.webtvcn.com\/2008\/abril\/padroflores.mp3\" target=\"_blank\"><font color=\"#0033cc\"><strong>OU&Ccedil;A E BAIXE ESSA PREGA&Ccedil;&Atilde;O NA &Iacute;NTEGRA<\/strong><\/font><\/a><\/p>\n<p>Jesus depois da ressurrei&ccedil;&atilde;o diz que primeiramente Ele vai ao Pai e l&aacute; preparar um lugar para cada um de n&oacute;s. <\/p>\n<p>  Muitas vezes pensamos nas coisas deste mundo e esquecemos-nos das coisas do c&eacute;u. Precisamos desejar o c&eacute;u.<\/p>\n<div id=\"foto\" style=\"margin: 0px auto;padding: 10px 0px;float: none;width: 350px\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2008\/abril\/17_eventos-003.jpg\" border=\"0\" width=\"350\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO--><br \/>&#039; Para chegar o c&eacute;u precisamos de um passaporte&#039;, diz&nbsp; Prado Flores<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesly Almeida <!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>  Para chegar o c&eacute;u precisamos de um passaporte depois de um visto. Qual &eacute; o passaporte para chega ao a c&eacute;u? O passaporte &eacute; o documento para chegar e sair dos pa&iacute;ses, e o passaporte para entrar no c&eacute;u &eacute; acreditar na miseric&oacute;rdia de Deus. Muita gente n&atilde;o acredita no amor de Deus, que &eacute; exagerado e vai al&eacute;m do nosso entendimento. <\/p>\n<p>   Tem uma hist&oacute;ria que diz que um homem muito bom chegou ao c&eacute;u, ele era um homem de devo&ccedil;&atilde;o, tocava no coro da igreja, mas quando ele bateu na porta, ele j&aacute; tinha certeza que ia para o c&eacute;u, dai S&atilde;o Pedro disse: Vamos v&ecirc; se voc&ecirc; com seus pontos entra no c&eacute;u. E ai o jovem disse tudo aquilo que faz na terra que cumulou ponto: eu ia a missa todo domingo, pagava os impostos, lia a Palavra de Deus semanalmente, cantava no coro,  fazia caridade, com tudo que o jovem falou  completou 14 pontos, mas para entrar no c&eacute;u precisava de 1000 pontos, mas ai ele falou: Ent&atilde;o vou precisar da miseric&oacute;rdia de Deus, e ai imediatamente S&atilde;o Pedro disse que ele j&aacute; tinha alcan&ccedil;ado 1000 pontos pois ele se reconheceu necessitado da miseric&oacute;rdia de Deus. <\/p>\n<p>  N&atilde;o temos pontos para nos salvar, mas a miseric&oacute;rdia de Deus nos salva, acredite em Jesus como sinal do amor de Deus. <\/p>\n<p>  No antigo testamente se as pessoas cumprissem a lei seriam salvas, se n&atilde;o cumprissem n&atilde;o era salvo, mas no novo testamento para ser salvo &eacute; preciso acreditar no Cristo, que &eacute; a prova do amor de Deus. <\/p>\n<p>  Mas para chegar ao c&eacute;u n&atilde;o basta apenas ter passaporte &eacute; preciso ter visto, e para ter o visto &eacute; preciso responder duas perguntas, voc&ecirc; foi feliz na terra? E a segunda pergunta &eacute;: Voc&ecirc; fez feliz algu&eacute;m na terra? Ao menos uma pessoa? <\/p>\n<p>  Para entrar no c&eacute;u &eacute; simples depende de voc&ecirc;. Quem voc&ecirc; faz feliz? Quem sorri com a sua presen&ccedil;a? <\/p>\n<p>  Imagina voc&ecirc; adentrando ao c&eacute;u e ai s&atilde;o Pedro pergunta voc&ecirc; tem passaporte, voc&ecirc; tem visto? <br \/> &Eacute; proibido est&aacute; triste podemos sofrer, mas &eacute; preciso ser feliz.<strong> O sinal dos crist&atilde;os n&atilde;o &eacute; a tristeza, mas a esperan&ccedil;a em meio a prova&ccedil;&atilde;o, n&atilde;o podemos levar o peso da cruz, mas o poder da cruz.<\/strong><\/p>\n<p>  Ainda &eacute; tempo de conseguir o passaporte e o visto para o c&eacute;u, aproveite o tempo e adquira o passaporte e o visto sendo feliz neste tempo.<\/p>\n<p><a href=\"http:\/\/vobr.webtvcn.com\/2008\/abril\/padroflores.mp3\" target=\"_blank\"><font color=\"#0033cc\"><\/font><\/a><\/p>\n<p><em>Transcri&ccedil;&atilde;o: Elcka Torres<br \/><\/em><\/p>\n<p><strong><\/p>\n<hr width=\"100%\" size=\"2\" \/><\/strong><\/p>\n<div align=\"center\"><strong><font size=\"2\">ADQUIRA ESSA PREGA&Ccedil;&Atilde;O PELO TELEFONE<\/font><br \/><font size=\"2\">(12) 3186-2600<\/font><\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"<p>OU&Ccedil;A E BAIXE ESSA PREGA&Ccedil;&Atilde;O NA &Iacute;NTEGRA Jesus depois da ressurrei&ccedil;&atilde;o diz que primeiramente Ele vai ao Pai e l&aacute; preparar um lugar para cada um de n&oacute;s. Muitas vezes pensamos nas coisas deste mundo e esquecemos-nos das coisas do&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/8929"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=8929"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/8929\/revisions"}],"predecessor-version":[{"id":8930,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/8929\/revisions\/8930"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=8929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=8929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=8929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}