{"id":9080,"date":"2008-09-18T11:55:00","date_gmt":"2008-09-18T14:55:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=9080"},"modified":"2014-08-13T04:57:52","modified_gmt":"2014-08-13T07:57:52","slug":"jesus-a-nova-e-a-eterna-alianca","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/jesus-a-nova-e-a-eterna-alianca\/","title":{"rendered":"Jesus a nova e a eterna alian\u00e7a"},"content":{"rendered":"<p>O Evangelho de Jo&atilde;o diz que &quot;Jesus passou a sua vida fazendo o bem a todos&quot;. Deus nos chama a alcan&ccedil;ar as coisas eternas que, hoje, est&atilde;o dispon&iacute;vel a n&oacute;s, como a Eucaristia. Jesus vai at&eacute; o fim e se consome na vontade do Pai.  <\/p>\n<p><font color=\"#0033cc\"><font color=\"#0033cc\"><font color=\"#0033cc\"><font color=\"#0033cc\"><font color=\"#0033cc\"><a href=\"http:\/\/vobr.webtvcn.com\/2008\/setembro\/padreadilson.mp3\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/cnova\/ministerio\/materias\/images\/03eos300d.jpg\" border=\"0\" width=\"72\" height=\"22\" align=\"left\" \/><\/a><a href=\"http:\/\/vobr.webtvcn.com\/2008\/setembro\/padreadilson.mp3\" target=\"_blank\"><font color=\"#0033cc\">Clique e ou&ccedil;a<\/font> na &iacute;ntegra<\/a><\/font><\/font><\/font><\/font><\/font><a href=\"http:\/\/vobr.webtvcn.com\/2008\/setembro\/padreadilson.mp3\" target=\"_blank\"><br \/><\/a><br \/>  &quot;Mas o Par&aacute;clito, o Esp&iacute;rito Santo, que o Pai enviar&aacute; em meu nome, ensinar-vos-&aacute; todas as coisas e vos recordar&aacute; tudo o que vos tenho dito.  Deixo-vos a paz, dou-vos a minha paz. N&atilde;o vo-la dou como o mundo a d&aacute;. N&atilde;o se perturbe o vosso cora&ccedil;&atilde;o, nem se atemorize! Ouvistes que eu vos disse: Vou e volto a v&oacute;s. Se me amardes, certamente haveis de alegrar-vos, que vou para junto do Pai, porque o Pai &eacute; maior do que eu.  E disse-vos agora estas coisas, antes que aconte&ccedil;am, para que creiais quando acontecerem.  J&aacute; n&atilde;o falarei muito convosco, porque vem o pr&iacute;ncipe deste mundo; mas ele n&atilde;o tem nada em mim.  O mundo, por&eacute;m, deve saber que amo o Pai e procedo como o Pai me ordenou. Levantai-vos, vamo-nos daqui&quot; (Jo&atilde;o 14,27-31).\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Evangelho de Jo&atilde;o diz que &quot;Jesus passou a sua vida fazendo o bem a todos&quot;. Deus nos chama a alcan&ccedil;ar as coisas eternas que, hoje, est&atilde;o dispon&iacute;vel a n&oacute;s, como a Eucaristia. Jesus vai at&eacute; o fim e se&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/9080"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=9080"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/9080\/revisions"}],"predecessor-version":[{"id":9081,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/9080\/revisions\/9081"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=9080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=9080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=9080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}