{"id":9168,"date":"2008-12-04T11:00:00","date_gmt":"2008-12-04T14:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=9168"},"modified":"2014-08-13T05:01:08","modified_gmt":"2014-08-13T08:01:08","slug":"sair-do-vale-da-lepra","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/sair-do-vale-da-lepra\/","title":{"rendered":"Sair do Vale da Lepra"},"content":{"rendered":"<div id=\"foto\" style=\"margin: 0pt auto;padding: 5px;width: 180px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2008\/novembro\/04_evenos-005.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Neil Velez<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida\/ Foto CN<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<div align=\"justify\"> Obrigada, Senhor, porque est&aacute;s aqui e porque nos d&aacute; a garantia de que contemplaremos a Sua gl&oacute;ria. Abra a sua b&iacute;blia no Evangelho de S&atilde;o Lucas 5, 12-13: <\/p>\n<p>  <em>&ldquo;Estando ele numa cidade, apareceu um homem cheio de lepra. Vendo Jesus, lan&ccedil;ou-se com o rosto por terra e lhe suplicou: Senhor, se queres, podes limpar-me. Jesus estendeu a m&atilde;o, tocou-o e disse: Eu quero; s&ecirc; purificado! No mesmo instante desapareceu dele a lepra&rdquo;.<\/em><\/p>\n<p>  Quando eu leio esta passagem b&iacute;blica sempre acho um pouco curioso porque est&aacute; enfermidade, naqueles dias, era considerada incur&aacute;vel. Toda pessoa que tinha essa doen&ccedil;a era separada da comunidade e enviada a outro lugar, conhecido como &ldquo;Vale da Lepra&rdquo;.<\/p>\n<p>  Se voc&ecirc; tinha essa enfermidade, a &uacute;nica forma de se incorporar na comunidade era se apresentando ao sacerdote. Ele fazia um estudo e dizia se voc&ecirc; estava curado ou n&atilde;o. As possibilidades da pessoa ser curada com essa doen&ccedil;a eram m&iacute;nimas. <\/p>\n<p>  Os leprosos viviam numa situa&ccedil;&atilde;o horr&iacute;vel. Se sa&iacute;ssem do Vale da Lepra sem permiss&atilde;o podiam receber um castigo forte; e se escondessem que tinham a doen&ccedil;a tamb&eacute;m recebiam o castigo. Em muitos casos, a morte era a puni&ccedil;&atilde;o. <\/p>\n<p>  Vemos nesta passagem que isso n&atilde;o acontece, que a lei da &eacute;poca n&atilde;o &eacute; cumprida. Algo se passou na vida desse leproso, retratado na b&iacute;blia, para que ele sa&iacute;sse do Vale da Lepra e fosse em busca de Jesus. Meus irm&atilde;os, se voc&ecirc; entrasse nesse lugar dali n&atilde;o saia. <\/p>\n<p>  Foi algu&eacute;m que o motivou a sair do Vale das Lepras para buscar a salva&ccedil;&atilde;o, a sua cura. As estat&iacute;sticas nos dizem que jamais na hist&oacute;ria do cristianismo se viu tantos pregadores como hoje em dia. As estat&iacute;sticas tamb&eacute;m nos dizem que s&atilde;o mais os que se perdem do que os que se salvam na atualidade. As almas est&atilde;o se perdendo. O que nos quer dizer isso?<\/p>\n<p>  N&atilde;o estamos levando a mensagem que Jesus quer, n&atilde;o estamos levando a Boa Nova. <strong>O que sai da nossa boca n&atilde;o &eacute; uma mensagem que produz f&eacute;. <\/strong>Eu imagino, quando leio esta passagem b&iacute;blica, que algu&eacute;m chegou ao Vale da Lepra e n&atilde;o levou uma mensagem de costume, levou um canto novo. Produziu esperan&ccedil;a em pessoas que n&atilde;o tinham esperan&ccedil;a.<\/p>\n<p>  Essa mensagem de esperan&ccedil;a fez com que esse homem sa&iacute;sse daquele lugar e fosse em busca da cura. <strong>Voc&ecirc; e eu temos um chamado: levar essa mensagem que produz esperan&ccedil;a.<\/strong> Muitas pessoas nos perguntas porque nos nossos encontros acontecem tantas curas e milagres e eu respondo que s&atilde;o por dois motivos. Primeiro porque n&atilde;o &eacute; um encontro conosco, mas com Deus; e segundo porque pregamos um Cristo que cura e salva.<\/p>\n<p>  A mensagem que hoje costuma-se escutar n&atilde;o &eacute; de um Jesus que cura e salva. N&oacute;s submetemos as pessoas ao Vale da Lepra, tiramos a esperan&ccedil;a delas, as acomodamos. Sabe, meu irm&atilde;o e minha irm&atilde;, hoje em dia estamos vendo um &ecirc;xodo muito grande na nossa Igreja, muitas pessoas est&atilde;o indo embora. <\/p>\n<p>  Jo&atilde;o Paulo II disse, h&aacute; uns sete anos, que a esperan&ccedil;a da Igreja estava na &Aacute;frica e na Am&eacute;rica Latina, locais estes onde predominava os cat&oacute;licos. No almanaque desse ano, vemos que esse cen&aacute;rio j&aacute; n&atilde;o &eacute; verdadeiro. Toda Am&eacute;rica Latina e &Aacute;frica j&aacute; corre muito risco com as seitas malignas.<\/p>\n<p>  Por que essas pessoas est&atilde;o indo embora da nossa Igreja? <strong>Eu creio que todos n&oacute;s buscamos Deus, mas nos equivocamos em procur&aacute;-Lo onde Ele n&atilde;o est&aacute;.<\/strong> O drogado, o alco&oacute;latra, o ad&uacute;ltero, por exemplo, todos andam buscando a Deus. Voc&ecirc; pode me perguntar agora: &ldquo;Mas como, Neil, que essas pessoas est&atilde;o buscando o Senhor?&rdquo; Sim, meus irm&atilde;os, eles andam tentando preencher um vazio que t&ecirc;m no cora&ccedil;&atilde;o, mas buscam Deus onde Ele n&atilde;o se encontra.<\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;padding: 5px;width: 370px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2008\/novembro\/04_evenos-004.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&quot;Necessitamos levar uma mensagem nova porque as almas est&atilde;o se perdendo e o inimigo est&aacute; ganhando a batalha&quot;<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida\/ Foto CN<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>Eles n&atilde;o t&ecirc;m culpa. N&oacute;s, sim, temos culpa. Eu e voc&ecirc; sabemos e conhecemos a verdade, sabemos que o &uacute;nico que preenche esse vazio &eacute; Cristo; mas n&atilde;o testemunhamos.  Deus deseja o melhor para n&oacute;s. Temos que o represent&aacute;-Lo. Esse &eacute; o Deus que temos que mostrar. O inimigo n&atilde;o quer que sa&iacute;amos do Vale da Lepra porque &eacute; nesse momento que a cura acontece e Deus &eacute; glorificado. <\/p>\n<p>  Deus deseja o melhor para n&oacute;s. A mensagem que est&atilde;o pregando n&atilde;o &eacute; a que leva a esperan&ccedil;a, n&atilde;o &eacute; a que est&aacute; produzindo f&eacute;. Estamos mal. As pessoas est&atilde;o indo embora da Igreja cat&oacute;lica porque estamos as acomodando no Vale da Lepra enquanto outros est&atilde;o oferecendo sa&iacute;das desse lugar. <\/p>\n<p>  Necessitamos levar uma mensagem nova porque as almas est&atilde;o se perdendo e o inimigo est&aacute; ganhando a batalha. &Eacute; tempo de anunciar um Cristo vivo, um Cristo que salva. <strong>Temos que dizer aos irm&atilde;os que aqui &eacute; a Igreja do Senhor; que n&atilde;o &eacute; pecado esperar na gl&oacute;ria de Deus.<\/strong><\/p>\n<p>  Pai, hoje eu te pe&ccedil;o, que o Senhor nos d&ecirc; esse poder para difundir a Sua palavra. Meus irm&atilde;os, somente cr&ecirc; no Senhor e ver&atilde;o a gl&oacute;ria. Confie&nbsp; n&#039;Ele, n&atilde;o deixe que as suas d&uacute;vidas te levem do Senhor. Deus &eacute; capaz! Que o Senhor aben&ccedil;oe a todos voc&ecirc;s. Am&eacute;m!<\/p><\/div>\n<p> <em>Transcri&ccedil;&atilde;o e adapta&ccedil;&atilde;o: Ariane Fonseca <\/em><\/p>\n<hr \/>\n<div align=\"center\"> <strong>ADQUIRA ESTA PALESTRA PELO TELEFONE (12) 3186 2600 <\/strong><\/div>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>Neil Velez Foto: Wesley Almeida\/ Foto CN Obrigada, Senhor, porque est&aacute;s aqui e porque nos d&aacute; a garantia de que contemplaremos a Sua gl&oacute;ria. Abra a sua b&iacute;blia no Evangelho de S&atilde;o Lucas 5, 12-13: &ldquo;Estando ele numa cidade, apareceu&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/9168"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=9168"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/9168\/revisions"}],"predecessor-version":[{"id":9169,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/9168\/revisions\/9169"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=9168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=9168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=9168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}